{"id":2728,"date":"2018-10-08T19:32:35","date_gmt":"2018-10-08T19:32:35","guid":{"rendered":"https:\/\/www.clausius.es\/politica-privacidad\/"},"modified":"2018-10-08T19:32:35","modified_gmt":"2018-10-08T19:32:35","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/www.clausius.es\/en\/politica-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<h3><span style=\"font-weight: 400;\">POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Respetando lo establecido en la legislaci\u00f3n vigente, Clausius (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Leyes que incorpora esta pol\u00edtica de privacidad<\/b><b><br \/>\n<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Esta pol\u00edtica de privacidad est\u00e1 adaptada a la normativa espa\u00f1ola y europea vigente en materia de protecci\u00f3n de datos personales en internet. En concreto, la misma respeta las siguientes normas: <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">El Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">El Real Decreto-ley 5\/2018, de 27 de julio, de medidas urgentes para la adaptaci\u00f3n del Derecho espa\u00f1ol a la normativa de la Uni\u00f3n Europea en materia de protecci\u00f3n de datos. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal (LOPD).<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">El Real Decreto 1720\/2007, de 21 de diciembre, por el que se aprueba el Reglamento de desarrollo de la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal (RDLOPD).<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La Ley 34\/ 2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE).<\/span><span style=\"font-weight: 400;\">\n<p><\/span><\/li>\n<\/ul>\n<p><b>Identidad del responsable del tratamiento de los datos personales <\/b><\/p>\n<p><b><br \/>\n<\/b><span style=\"font-weight: 400;\">El responsable del tratamiento de los datos personales recogidos en Clausius.es, es: Ceo2green, S.L., provista de NIF: B27806801 e inscrita en el Registro mercantil de Pontevedra con los siguientes datos registrales: Tomo 3984, Folio 110, Hoja PO-572158, inscripci\u00f3n 1\u00aa. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sus datos de contacto son los siguientes: <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Direcci\u00f3n: Estrada pola v\u00eda, 27H 36350 Nigr\u00e1n-Pontevedra<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E-mail de contacto: <\/span><a href=\"mailto:info@ceo2green.com\"><span style=\"font-weight: 400;\">info@ceo2green.com<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Estas condiciones tambi\u00e9n regulan el uso a otras p\u00e1ginas web de las que\u00a0<\/span><b>Ceo2gren <\/b><span style=\"font-weight: 400;\">es titular, como son:\u00a0<\/span><a href=\"http:\/\/ceo2green.com\"><span style=\"font-weight: 400;\">http:\/\/ceo2green.com<\/span><\/a><\/p>\n<p><b>Registro de datos de car\u00e1cter personal <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales recabados por Clausius, mediante los formularios extendidos en sus p\u00e1ginas, ser\u00e1n introducidos en un fichero automatizado bajo la responsabilidad del Responsable del tratamiento, y debidamente declarado e inscrito en el Registro General de la Agencia de Protecci\u00f3n de Datos que se puede consultar en el sitio web de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (htp:\/\/www.agpd.es), con la finalidad de poder facilitar, agilizar y cumplir los compromisos establecidos entre Clausius y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este rellene, o para atender una solicitud o consulta del mismo. <\/span><\/p>\n<p><b>Principios aplicables al tratamiento de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El tratamiento de los datos personales del Usuario se someter\u00e1 a los siguientes principios recogidos en el art\u00edculo 5 del RGPD:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de licitud, lealtad y transparencia: se requerir\u00e1 en todo momento el consentimiento del Usuario previa informaci\u00f3n completamente transparente de los fines para los cuales se recogen los datos personales. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de limitaci\u00f3n de la finalidad: los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de minimizaci\u00f3n de datos: los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de exactitud: los datos personales deben ser exactos y estar siempre actualizados. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de limitaci\u00f3n del plazo de conservaci\u00f3n: los datos personales solo ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n del Usuario durante el tiempo necesario para los fines de su tratamiento. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de integridad y confidencialidad: los datos personales ser\u00e1n tratados de manera que se garantice su seguridad y confidencialidad. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Principio de responsabilidad proactiva: el Responsable del tratamiento ser\u00e1 responsable de asegurar que los principios anteriores se cumplen. <\/span><span style=\"font-weight: 400;\">\n<p><\/span><\/li>\n<\/ul>\n<p><b>Categor\u00edas de datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Las categor\u00edas de datos que se tratan en Clausius son \u00fanicamente datos identificativos. En ning\u00fan caso, se tratan categor\u00edas especiales de datos personales en el sentido del art\u00edculo 9 del RGPD.<\/span><\/p>\n<p><b>Base legal para el tratamiento de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La base legal para el tratamiento de los datos personales es el consentimiento. Clausius se compromete a recabar el consentimiento expreso y verificable del Usuario para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Usuario tendr\u00e1 derecho a retirar su consentimiento en cualquier momento. Ser\u00e1 tan f\u00e1cil retirar el consentimiento como darlo. Como regla general, la retirada del consentimiento no condicionar\u00e1 el uso del sitio Web. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En las ocasiones en las que el Usuario deba o pueda facilitar sus datos a trav\u00e9s de formularios para realizar consultas, solicitar informaci\u00f3n o por motivos relacionados con el sitio Web, se le informar\u00e1 en caso de que la cumplimentaci\u00f3n de alguno de ellos sea obligatoria debido a que los mismos sean imprescindibles para el correcto desarrollo de la operaci\u00f3n realizada. <\/span><\/p>\n<p><b>Per\u00edodos de retenci\u00f3n de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales solo ser\u00e1n retenidos durante el tiempo necesario para los fines de su tratamiento y, en todo caso hasta que el usuario solicite su supresi\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del plazo durante el cual se conservar\u00e1n los datos personales o, cuando esto no sea posible, los criterios utilizados para determinar este plazo. <\/span><\/p>\n<p><b>Destinatarios de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales del Usuario no ser\u00e1n compartidos con terceros. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cualquier caso, en el momento en que se obtengan los datos personales, se informar\u00e1 al usuario acerca de los destinatarios o las categor\u00edas de destinatarios de los datos personales. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Datos personales de menores de edad<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Respetando lo establecido en los art\u00edculos 8 del RGPD y 13 del RDLOPD, solo los mayores de 14 a\u00f1os podr\u00e1n otorgar su consentimiento para el tratamiento de sus datos personales de forma il\u00edcita por Clausius. Si se trata de un menor de 14 a\u00f1os, ser\u00e1 necesario el consentimiento de los padres o tutores para el tratamiento, y este solo se considerar\u00e1 l\u00edcito en la medida en la que los mismos lo hayan autorizado. <\/span><\/p>\n<p><b>Secreto y seguridad de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Clausius se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos, de forma que se garantice la seguridad de los datos de car\u00e1cter personal y se evite la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, debido a que Clausius no puede garantizar la impugnabilidad de internet ni la ausencia total de hackers u otros que accedan de modo fraudulento a los datos personales, el Responsable del tratamiento se compromete a comunicar al Usuario sin dilaci\u00f3n indebida cuando ocurra una violaci\u00f3n de la seguridad de los datos personales que sea probable que entra\u00f1e un alto riesgo para los derechos y libertades de las personas f\u00edsicas. Siguiendo lo establecido en el art\u00edculo 4 del RGPD, se entiende por violaci\u00f3n de la seguridad de los datos personales toda violaci\u00f3n de la seguridad que ocasione la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales ser\u00e1n tratados como confidenciales por el Responsable del tratamiento, quien se compromete a informar de y a garantizar por medio de una obligaci\u00f3n legal o contractual que dicha confidencialidad sea respetada por sus empleados, asociados, y toda persona a la cual le haga accesible la informaci\u00f3n. <\/span><\/p>\n<p><b>Derechos derivados del tratamiento de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El Usuario tiene sobre Clausius y podr\u00e1, por tanto, ejercer frente al Responsable del tratamiento los siguientes derechos reconocidos en el RGPD: <\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho de acceso<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario a obtener confirmaci\u00f3n de si Clausius est\u00e1 tratando o no sus datos personales y, en caso afirmativo, obtener informaci\u00f3n sobre sus datos concretos de car\u00e1cter personal y del tratamiento que Clausius haya realizado o realice, as\u00ed como, entre otra, de la informaci\u00f3n disponible sobre el origen de dichos datos y los destinatarios de las comunicaciones realizadas o previstas de los mismos. <\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho de rectificaci\u00f3n<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario a que se modifiquen sus datos personales que resulten ser inexactos o, teniendo en cuenta los fines del tratamiento, incompletos.<\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho de supresi\u00f3n (\u201cel derecho al olvido\u201d)<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario, siempre que la legislaci\u00f3n vigente no establezca lo contrario, a obtener la supresi\u00f3n de sus datos personales cuando estos ya no sean necesarios para los fines para los cuales fueron recogidos o tratados; el Usuario haya retirado su consentimiento al tratamiento y este no cuente con otra base legal; el Usuario se oponga al tratamiento y no exista otro motivo leg\u00edtimo para continuar con el mismo; los datos personales hayan sido tratados il\u00edcitamente; los datos personales deban suprimirse en cumplimiento de una obligaci\u00f3n legal; o los datos personales hayan sido obtenidos producto de una oferta directa de servicios de la sociedad de la informaci\u00f3n a un menor de 14 a\u00f1os. Adem\u00e1s de suprimir los datos, el Responsable del tratamiento, teniendo en cuenta la tecnolog\u00eda disponible y el coste de su aplicaci\u00f3n, deber\u00e1 adoptar medidas razonables para informar a los responsables que est\u00e9n tratando los datos personales de la solicitud del interesado de supresi\u00f3n de cualquier enlace a esos datos personales. <\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho a la limitaci\u00f3n del tratamiento<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario a limitar el tratamiento de sus datos personales. El Usuario tiene derecho a obtener la limitaci\u00f3n del tratamiento cuando impugne la exactitud de sus datos personales, el tratamiento sea il\u00edcito; el Responsable del tratamiento ya no necesite los datos personales, pero el Usuario lo necesite para hacer reclamaciones; y cuando el Usuario se haya opuesto al tratamiento. <\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho a la portabilidad de los datos<\/span><\/i><span style=\"font-weight: 400;\">: En caso de que el tratamiento se efect\u00fae por medios automatizados, el Usuario tendr\u00e1 derecho a recibir del Responsable del tratamiento sus datos personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a transmitirlos a otro responsable del tratamiento. Siempre que sea t\u00e9cnicamente posible, el Responsable del tratamiento transmitir\u00e1 directamente los datos a ese otro responsable. <\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho de oposici\u00f3n<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de Clausius.<\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho de oposici\u00f3n<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de Clausius.<\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en el tratamiento automatizado, incluida la elaboraci\u00f3n de perfiles<\/span><\/i><span style=\"font-weight: 400;\">: Es el derecho del usuario a no ser objeto de una decisi\u00f3n individualizada basada \u00fanicamente en el tratamiento automatizado de sus datos personales, incluida la elaboraci\u00f3n de perfiles, existente salo que la legislaci\u00f3n vigente establezca lo contrario. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">As\u00ed pues, el Usuario podr\u00e1 ejercitar sus derechos mediante comunicaci\u00f3n escrita dirigida al Responsable del tratamiento con la referencia \u201cRGPD-www.clausius.es\u201d especificando: <\/span><span style=\"font-weight: 400;\"><\/p>\n<p><\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nombre, apellidos del Usuario y copia del DNI. En los casos en que se admita la representaci\u00f3n, ser\u00e1 tambi\u00e9n necesaria la identificaci\u00f3n por el mismo medio de la persona que representa al Usuario, as\u00ed como el documento acreditativo de la representaci\u00f3n. La fotocopia del DNI podr\u00e1 ser sustituida, por cualquier otro medio v\u00e1lido en derecho que acredite la identidad. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Petici\u00f3n con los motivos espec\u00edficos de la solicitud o informaci\u00f3n a la que se quiere acceder. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Domicilio a efecto de notificaciones. <\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Fecha y firma del solicitante<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Todo documento que acredite la petici\u00f3n que formula. <\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Esta solicitud y todo otro documento adjunto podr\u00e1 enviarse a la siguiente direcci\u00f3n y\/o correo electr\u00f3nico: <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Direcci\u00f3n postal: <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estrada pola v\u00eda, 27-H 36350 Nigr\u00e1n (Pontevedra)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Correo electr\u00f3nico: <\/span><a href=\"mailto:info@ceo2green.com\"><span style=\"font-weight: 400;\">info@ceo2green.com<\/span><\/a><\/p>\n<p><b>Derechos derivados del tratamiento de los datos personales<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El sitio Web puede incluir hiperv\u00ednculos o enlaces que permiten acceder a p\u00e1ginas web de terceros distintos de Clausius.es, y que por tanto no son operados por Clausius. Los titulares de dichos sitios web dispondr\u00e1n de sus propias pol\u00edticas de protecci\u00f3n de datos, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad. <\/span><\/p>\n<p><b>Reclamaciones ante la autoridad de control<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En caso de que el Usuario considere que existe un problema o infracci\u00f3n de la normativa vigente en la forma en la que se est\u00e1n tratando sus datos personales, tendr\u00e1 derecho a la tutela judicial efectiva y a presentar una reclamaci\u00f3n ante una autoridad de control, en particular, en el Estado en el que tenga su residencia habitual, lugar de trabajo o lugar de la supuesta infracci\u00f3n. En el caso de Espa\u00f1a, la autoridad de control es la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (<\/span><a href=\"http:\/\/www.agpd.es\"><span style=\"font-weight: 400;\">http:\/\/www.agpd.es<\/span><\/a><span style=\"font-weight: 400;\">).<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>ACEPTACI\u00d3N DE CAMBIOS EN ESTA POL\u00cdTICA DE PRIVACIDAD<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Es necesario que el Usuario haya le\u00eddo y est\u00e9 conforme con las condiciones sobre la protecci\u00f3n de datos de car\u00e1cter personal contenidas en esta Pol\u00edtica de Privacidad, as\u00ed como que acepte el tratamiento de sus datos personales para que el Responsable del tratamiento pueda proceder al mismo en la forma, durante los plazos y para las finalidades indicadas. El uso del Sitio Web implicar\u00e1 la aceptaci\u00f3n de la Pol\u00edtica de Privacidad del mismo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Clausius se reserva el derecho a modificar su Pol\u00edtica de Privacidad, de acuerdo a su propio criterio, o motivado por un cambio legislativo, jurisprudencial o doctrinal de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Los cambios o actualizaciones de esta Pol\u00edtica de Privacidad ser\u00e1n notificados de forma expl\u00edcita al Usuario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta Pol\u00edtica de Privacidad fue actualizada el d\u00eda 28 de noviembre de 2018 para adaptarse al Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Clausius (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de privacidad est\u00e1 adaptada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2728","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad - Clausius<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clausius.es\/en\/politica-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - Clausius\" \/>\n<meta property=\"og:description\" content=\"POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Clausius (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de privacidad est\u00e1 adaptada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clausius.es\/en\/politica-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Clausius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clausius.es\\\/en\\\/politica-privacidad\\\/\",\"url\":\"https:\\\/\\\/www.clausius.es\\\/en\\\/politica-privacidad\\\/\",\"name\":\"Pol\u00edtica de privacidad - Clausius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clausius.es\\\/#website\"},\"datePublished\":\"2018-10-08T19:32:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clausius.es\\\/en\\\/politica-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clausius.es\\\/en\\\/politica-privacidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clausius.es\\\/en\\\/politica-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.clausius.es\\\/en\\\/portada\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clausius.es\\\/#website\",\"url\":\"https:\\\/\\\/www.clausius.es\\\/\",\"name\":\"Clausius\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clausius.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Clausius","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clausius.es\/en\/politica-privacidad\/","og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica de privacidad - Clausius","og_description":"POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Clausius (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de privacidad est\u00e1 adaptada [&hellip;]","og_url":"https:\/\/www.clausius.es\/en\/politica-privacidad\/","og_site_name":"Clausius","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clausius.es\/en\/politica-privacidad\/","url":"https:\/\/www.clausius.es\/en\/politica-privacidad\/","name":"Pol\u00edtica de privacidad - Clausius","isPartOf":{"@id":"https:\/\/www.clausius.es\/#website"},"datePublished":"2018-10-08T19:32:35+00:00","breadcrumb":{"@id":"https:\/\/www.clausius.es\/en\/politica-privacidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clausius.es\/en\/politica-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clausius.es\/en\/politica-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clausius.es\/en\/portada\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.clausius.es\/#website","url":"https:\/\/www.clausius.es\/","name":"Clausius","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clausius.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/pages\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/comments?post=2728"}],"version-history":[{"count":1,"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/pages\/2728\/revisions"}],"predecessor-version":[{"id":2730,"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/pages\/2728\/revisions\/2730"}],"wp:attachment":[{"href":"https:\/\/www.clausius.es\/en\/wp-json\/wp\/v2\/media?parent=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}